{"id":13799,"date":"2025-09-02T15:00:31","date_gmt":"2025-09-02T12:00:31","guid":{"rendered":"https:\/\/cse-net.org\/?p=13799"},"modified":"2025-09-01T17:45:05","modified_gmt":"2025-09-01T14:45:05","slug":"california-sb253-scope3-baseline","status":"publish","type":"post","link":"https:\/\/cse-net.org\/fr\/california-sb253-scope3-baseline\/","title":{"rendered":"California SB 253 Perspectives : Comment cr\u00e9er une base de r\u00e9f\u00e9rence cr\u00e9dible pour les \u00e9missions du champ d'application 3"},"content":{"rendered":"<p data-start=\"700\" data-end=\"1251\">\n<p data-start=\"700\" data-end=\"1251\">Californie <a class=\"decorated-link cursor-pointer\" href=\"https:\/\/leginfo.legislature.ca.gov\/faces\/billNavClient.xhtml?bill_id=202320240SB253\" target=\"_new\" rel=\"noopener\" data-start=\"713\" data-end=\"850\">Loi sur la responsabilit\u00e9 des entreprises en mati\u00e8re de climat (SB 253)<\/a> est en train de remodeler la divulgation d'informations sur le climat par les entreprises aux \u00c9tats-Unis. \u00c0 partir de 2026, les grandes entreprises op\u00e9rant en Californie seront tenues de d\u00e9clarer leurs \u00e9missions des champs 1, 2 et 3, conform\u00e9ment aux normes mondiales de transparence. Pour la plupart des entreprises, les \u00e9missions de type 3, qui couvrent la cha\u00eene de valeur depuis les fournisseurs jusqu'\u00e0 l'utilisation des produits, repr\u00e9sentent la part la plus importante et la plus complexe de leur empreinte carbone.<\/p>\n<p data-start=\"1253\" data-end=\"1449\">La premi\u00e8re \u00e9tape essentielle de la mise en conformit\u00e9 consiste \u00e0 cr\u00e9er une base de r\u00e9f\u00e9rence cr\u00e9dible pour les \u00e9missions du champ d'application 3. Sans cette base, les entreprises risquent de faire des d\u00e9clarations erron\u00e9es, d'\u00eatre soumises \u00e0 un examen r\u00e9glementaire ou d'\u00eatre accus\u00e9es d'\u00e9coblanchiment.<\/p>\n<h3 data-start=\"1451\" data-end=\"1488\"><\/h3>\n<h3 data-start=\"1451\" data-end=\"1488\">Pourquoi le champ d'application 3 est au c\u0153ur du projet SB 253<\/h3>\n<p data-start=\"1490\" data-end=\"1844\">Contrairement aux \u00e9missions des champs d'application 1 et 2, que les entreprises peuvent mesurer directement par leurs activit\u00e9s et leur consommation d'\u00e9nergie, les \u00e9missions du champ d'application 3 comprennent les \u00e9missions indirectes dans 15 cat\u00e9gories d\u00e9finies par l'Organisation mondiale de la sant\u00e9. <a class=\"decorated-link cursor-pointer\" href=\"https:\/\/ghgprotocol.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"1666\" data-end=\"1706\">Protocole des GES<\/a>. Il s'agit des biens et services achet\u00e9s, des voyages d'affaires, des transports, des d\u00e9chets et m\u00eame de l'utilisation en aval des produits vendus.<\/p>\n<p data-start=\"1846\" data-end=\"2298\">Les l\u00e9gislateurs californiens ont con\u00e7u la loi SB 253 pour s'assurer que la responsabilit\u00e9 des entreprises en mati\u00e8re de climat refl\u00e8te l'ensemble de la cha\u00eene de valeur, et pas seulement les op\u00e9rations internes. Cette mesure refl\u00e8te les cadres internationaux tels que la Convention-cadre des Nations unies sur les changements climatiques (CCNUCC). <a class=\"decorated-link cursor-pointer\" href=\"https:\/\/www.efrag.org\/en\" target=\"_new\" rel=\"noopener\" data-start=\"2039\" data-end=\"2119\">Normes europ\u00e9ennes d'information sur le d\u00e9veloppement durable (ESRS)<\/a> et le <a class=\"decorated-link cursor-pointer\" href=\"https:\/\/sciencebasedtargets.org\/\" target=\"_new\" rel=\"noopener\" data-start=\"2128\" data-end=\"2203\">Initiative sur les objectifs scientifiques (SBTi)<\/a>qui mettent tous deux l'accent sur la d\u00e9claration du champ d'application 3 en tant qu'\u00e9l\u00e9ment essentiel de la d\u00e9carbonisation fond\u00e9e sur la science.<\/p>\n<h3 data-start=\"2300\" data-end=\"2340\"><\/h3>\n<h3 data-start=\"2300\" data-end=\"2340\">Les d\u00e9fis des bases de r\u00e9f\u00e9rence du champ d'application 3<\/h3>\n<p data-start=\"2342\" data-end=\"2500\">L'\u00e9tablissement d'une base de r\u00e9f\u00e9rence cr\u00e9dible pour le champ d'application 3 est un d\u00e9fi car il n\u00e9cessite la collecte de donn\u00e9es en dehors du contr\u00f4le direct de l'entreprise. Les obstacles les plus courants sont les suivants :<\/p>\n<ul data-start=\"2502\" data-end=\"2909\">\n<li data-start=\"2502\" data-end=\"2579\">\n<p data-start=\"2504\" data-end=\"2579\">Lacunes dans les donn\u00e9es : Les fournisseurs peuvent ne pas disposer des syst\u00e8mes n\u00e9cessaires pour mesurer ou d\u00e9clarer les \u00e9missions.<\/p>\n<\/li>\n<li data-start=\"2580\" data-end=\"2681\">\n<p data-start=\"2582\" data-end=\"2681\">M\u00e9thodes incoh\u00e9rentes : Diff\u00e9rents fournisseurs et partenaires peuvent utiliser des m\u00e9thodes de calcul diff\u00e9rentes.<\/p>\n<\/li>\n<li data-start=\"2682\" data-end=\"2789\">\n<p data-start=\"2684\" data-end=\"2789\">Transparence limit\u00e9e : Les fournisseurs de petite taille ou internationaux peuvent \u00eatre r\u00e9ticents \u00e0 partager des informations sensibles.<\/p>\n<\/li>\n<li data-start=\"2790\" data-end=\"2909\">\n<p data-start=\"2792\" data-end=\"2909\">Des cha\u00eenes de valeur dynamiques : Les fusions, les nouveaux fournisseurs et l'\u00e9volution du comportement des consommateurs compliquent la coh\u00e9rence d'une ann\u00e9e sur l'autre.<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"2911\" data-end=\"3019\">Malgr\u00e9 ces obstacles, les entreprises doivent \u00e9tablir une base de r\u00e9f\u00e9rence qui soit transparente, d\u00e9fendable et v\u00e9rifiable.<\/p>\n<h3 data-start=\"3021\" data-end=\"3069\"><\/h3>\n<h3 data-start=\"3021\" data-end=\"3069\">\u00c9tapes de la cr\u00e9ation d'une base de r\u00e9f\u00e9rence cr\u00e9dible pour le champ d'application 3<\/h3>\n<h4 data-start=\"3071\" data-end=\"3123\">1. D\u00e9finir les limites et hi\u00e9rarchiser les cat\u00e9gories<\/h4>\n<p data-start=\"3124\" data-end=\"3341\">Commencez par une \u00e9valuation de la mat\u00e9rialit\u00e9 afin d'identifier les cat\u00e9gories du champ d'application 3 les plus pertinentes. Par exemple, une entreprise de vente au d\u00e9tail peut se concentrer sur les biens achet\u00e9s, tandis qu'une entreprise technologique peut mettre l'accent sur les \u00e9missions li\u00e9es \u00e0 la phase d'utilisation du produit.<\/p>\n<h4 data-start=\"3343\" data-end=\"3384\">2. S'aligner sur les normes \u00e9tablies<\/h4>\n<p data-start=\"3385\" data-end=\"3646\">Utilisez des cadres tels que le <a class=\"decorated-link cursor-pointer\" href=\"https:\/\/ghgprotocol.org\/corporate-value-chain-scope-3-standard\" target=\"_new\" rel=\"noopener\" data-start=\"3409\" data-end=\"3506\">Norme de la cha\u00eene de valeur de l'entreprise du GHG Protocol<\/a> et des syst\u00e8mes d'information tels que <a class=\"decorated-link cursor-pointer\" target=\"_new\" rel=\"noopener\" data-start=\"3537\" data-end=\"3566\">CDP<\/a>. L'alignement garantit la comparabilit\u00e9 et r\u00e9duit le risque de r\u00e9actions n\u00e9gatives de la part des autorit\u00e9s r\u00e9glementaires.<\/p>\n<h4 data-start=\"3648\" data-end=\"3692\">3. Collecter des donn\u00e9es primaires dans la mesure du possible<\/h4>\n<p data-start=\"3693\" data-end=\"3903\">Engager les principaux fournisseurs \u00e0 collecter des donn\u00e9es sur les \u00e9missions r\u00e9elles au lieu de s'appuyer uniquement sur des moyennes ou des approximations. Commencez par les fournisseurs de niveau 1 et \u00e9tendez-les au fil du temps. La formation des fournisseurs et les incitations peuvent am\u00e9liorer la pr\u00e9cision des donn\u00e9es.<\/p>\n<h4 data-start=\"3905\" data-end=\"3939\">4. Utiliser les donn\u00e9es secondaires \u00e0 bon escient<\/h4>\n<p data-start=\"3940\" data-end=\"4213\">Pour les cat\u00e9gories pour lesquelles les donn\u00e9es primaires ne sont pas disponibles, il convient d'utiliser des facteurs d'\u00e9mission de haute qualit\u00e9 provenant de sources telles que l'EPA's <a class=\"decorated-link\" href=\"https:\/\/www.epa.gov\/climateleadership\/ghg-emission-factors-hub\" target=\"_new\" rel=\"noopener\" data-start=\"4048\" data-end=\"4134\">Facteurs d'\u00e9mission Hub<\/a> ou des bases de donn\u00e9es sectorielles. Toujours divulguer les hypoth\u00e8ses et les \u00e9valuations de la qualit\u00e9 des donn\u00e9es.<\/p>\n<h4 data-start=\"4215\" data-end=\"4260\">5. Documenter les m\u00e9thodologies de mani\u00e8re transparente<\/h4>\n<p data-start=\"4261\" data-end=\"4424\">Conserver un enregistrement clair de toutes les m\u00e9thodes de calcul, des hypoth\u00e8ses et des limites. Cela sera essentiel pour l'assurance d'une tierce partie, que SB 253 exige d'ici 2030.<\/p>\n<h4 data-start=\"4426\" data-end=\"4486\">6. \u00c9tablir une base de r\u00e9f\u00e9rence pour la premi\u00e8re ann\u00e9e et proc\u00e9der \u00e0 des am\u00e9liorations it\u00e9ratives<\/h4>\n<p data-start=\"4487\" data-end=\"4689\">La premi\u00e8re ann\u00e9e de d\u00e9claration peut s'appuyer sur des estimations, mais la base de r\u00e9f\u00e9rence doit servir de cadre \u00e9volutif. Les entreprises doivent am\u00e9liorer la qualit\u00e9 des donn\u00e9es, \u00e9tendre la couverture des fournisseurs et affiner les m\u00e9thodologies chaque ann\u00e9e.<\/p>\n<h3 data-start=\"4691\" data-end=\"4741\"><\/h3>\n<h3 data-start=\"4691\" data-end=\"4741\">Transformer la conformit\u00e9 en avantage concurrentiel<\/h3>\n<p data-start=\"4743\" data-end=\"4952\">Plut\u00f4t que de consid\u00e9rer le SB 253 comme un fardeau de conformit\u00e9, les entreprises avant-gardistes le voient comme une opportunit\u00e9 de renforcer les cha\u00eenes d'approvisionnement et la confiance des investisseurs. Une solide base de r\u00e9f\u00e9rence Scope 3 permet aux organisations de.. :<\/p>\n<ul data-start=\"4954\" data-end=\"5178\">\n<li data-start=\"4954\" data-end=\"5001\">\n<p data-start=\"4956\" data-end=\"5001\">Suivre les progr\u00e8s accomplis dans la r\u00e9alisation des objectifs scientifiques<\/p>\n<\/li>\n<li data-start=\"5002\" data-end=\"5064\">\n<p data-start=\"5004\" data-end=\"5064\">Identifier les points n\u00e9vralgiques pour la r\u00e9duction des \u00e9missions et des co\u00fbts<\/p>\n<\/li>\n<li data-start=\"5065\" data-end=\"5112\">\n<p data-start=\"5067\" data-end=\"5112\">Renforcer les relations avec les fournisseurs<\/p>\n<\/li>\n<li data-start=\"5113\" data-end=\"5178\">\n<p data-start=\"5115\" data-end=\"5178\">Renforcer la cr\u00e9dibilit\u00e9 aupr\u00e8s des investisseurs, des r\u00e9gulateurs et des clients<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"5180\" data-end=\"5314\">\u00c0 mesure que les r\u00e8gles de divulgation de l'information sur le climat de la SEC am\u00e9ricaine et les normes ESG mondiales \u00e9voluent, une base de r\u00e9f\u00e9rence solide pour le champ d'application 3 permet d'\u00eatre pr\u00eat au-del\u00e0 de la Californie.<\/p>\n<h3 data-start=\"5316\" data-end=\"5351\"><\/h3>\n<h3 data-start=\"5316\" data-end=\"5351\">Pr\u00e9parer votre \u00e9quipe au SB 253<\/h3>\n<p data-start=\"5353\" data-end=\"5598\">Le passage de l'information volontaire \u00e0 l'information obligatoire et garantie exigera de nouvelles comp\u00e9tences et une nouvelle expertise de la part des \u00e9quipes charg\u00e9es du d\u00e9veloppement durable, des d\u00e9partements financiers et des responsables de la cha\u00eene d'approvisionnement. La formation est essentielle pour garder une longueur d'avance sur les risques de conformit\u00e9.<\/p>\n<p data-start=\"5600\" data-end=\"5860\">C'est pourquoi la <a class=\"decorated-link\" href=\"https:\/\/cse-net.org\/fr\/trainings\/usa-sustainability-esg-course-cohort3-2\/\" target=\"_new\" rel=\"noopener\" data-start=\"5615\" data-end=\"5753\">Programme des praticiens certifi\u00e9s en mati\u00e8re de d\u00e9veloppement durable - \u00e9dition avanc\u00e9e<\/a> est con\u00e7u pour fournir aux professionnels des outils pratiques pour r\u00e9pondre aux exigences du SB 253. Le programme couvre :<\/p>\n<ul data-start=\"5862\" data-end=\"6057\">\n<li data-start=\"5862\" data-end=\"5909\">\n<p data-start=\"5864\" data-end=\"5909\">Calcul et d\u00e9claration des \u00e9missions du champ d'application 3<\/p>\n<\/li>\n<li data-start=\"5910\" data-end=\"5952\">\n<p data-start=\"5912\" data-end=\"5952\">Double \u00e9valuation de l'importance relative et des risques<\/p>\n<\/li>\n<li data-start=\"5953\" data-end=\"5994\">\n<p data-start=\"5955\" data-end=\"5994\">Notations ESG et attentes des investisseurs<\/p>\n<\/li>\n<li data-start=\"5995\" data-end=\"6057\">\n<p data-start=\"5997\" data-end=\"6057\">Meilleures pratiques pour l'engagement des fournisseurs et la collecte de donn\u00e9es<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"6059\" data-end=\"6592\">\ud83d\udc49 <a class=\"decorated-link cursor-pointer\" href=\"https:\/\/www.eventbrite.com\/e\/certified-sustainability-practitioner-program-advanced-edition-2025-tickets-1383539406609?aff=oddtdtcreator&amp;_gl=1*l3ulqy*_gcl_aw*R0NMLjE3NTU1MjAzODIuQ2owS0NRancySURGQmhEQ0FSSXNBQkRLT0o3RjRibldWVnZLMkw3WmZIMk0tbUNLeGJZMl80TXduMXN6ZjVSR21URkxXb0NITDBDRVAta2FBc1hjRUFMd193Y0I.*_gcl_au*MTUxNjk4NjA4OC4xNzU2NzM1Mzk5*_ga*MzQ4NjkzODQuMTc0ODk1MzAyNw..*_ga_ZQVN22WE09*czE3NTY3MzUzOTkkbzE0MyRnMSR0MTc1NjczNzIzOSRqNjAkbDAkaDI0MzkwMDgwNg..\" target=\"_new\" rel=\"noopener\" data-start=\"6062\" data-end=\"6590\">S'inscrire ici via Eventbrite<\/a><\/p>\n<p data-start=\"6594\" data-end=\"6775\">En commen\u00e7ant d\u00e8s aujourd'hui, les professionnels du d\u00e9veloppement durable peuvent transformer la conformit\u00e9 en leadership - et s'assurer que leurs organisations sont pleinement pr\u00e9par\u00e9es \u00e0 la loi californienne historique sur le climat.<\/p>\n<p data-start=\"6594\" data-end=\"6775\">","protected":false},"excerpt":{"rendered":"<p>California\u2019s Climate Corporate Data Accountability Act (SB 253) is reshaping corporate climate disclosure in the United States. Starting in 2026, large companies operating in California will be required to report Scope 1, 2, and 3 emissions, aligning with global transparency standards. For most organizations, Scope 3 emissions, which cover the value chain from suppliers to [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":13800,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1414,1574,1587,1594,1843,1844,28,33,34,35,1283,1286],"tags":[580,1167,1535,1713,1941,2284],"class_list":["post-13799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esg-reporting","category-north-america","category-canada","category-esg-investment","category-green-skils","category-green-skills","category-news","category-corporate-sustainability","category-sustainability","category-sustainability-training","category-sustainability-reporting-services","category-strategies-with-an-impact","tag-esg-reporting","tag-scope-3-emissions","tag-sb-253","tag-sustainability-compliance","tag-u-s-companies","tag-california-climate-disclosure"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>California SB 253: Building a Credible Scope 3 Baseline<\/title>\n<meta name=\"description\" content=\"Learn how U.S. companies can establish credible Scope 3 emissions baselines under California\u2019s SB 253. Discover key steps and data challenges.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cse-net.org\/fr\/california-sb253-scope3-baseline\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"California SB 253: Building a Credible Scope 3 Baseline\" \/>\n<meta property=\"og:description\" content=\"Learn how U.S. companies can establish credible Scope 3 emissions baselines under California\u2019s SB 253. Discover key steps and data challenges.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cse-net.org\/fr\/california-sb253-scope3-baseline\/\" \/>\n<meta property=\"og:site_name\" content=\"Center for Sustainbability &amp; Excellence\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Centre.for.Sustainability.and.Excellence\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-02T12:00:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cse-net.org\/wp-content\/uploads\/2025\/09\/blogs-v2-2025-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"cseadm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CSE_network\" \/>\n<meta name=\"twitter:site\" content=\"@CSE_network\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cseadm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cse-net.org\\\/california-sb253-scope3-baseline\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/california-sb253-scope3-baseline\\\/\"},\"author\":{\"name\":\"cseadm\",\"@id\":\"https:\\\/\\\/cse-net.org\\\/#\\\/schema\\\/person\\\/3615f0465d5060787c50f34130070382\"},\"headline\":\"California SB 253 Perspectives: How to Create a Credible Baseline for Scope 3 Emissions\",\"datePublished\":\"2025-09-02T12:00:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/california-sb253-scope3-baseline\\\/\"},\"wordCount\":684,\"publisher\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/california-sb253-scope3-baseline\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cse-net.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/blogs-v2-2025-5.png\",\"keywords\":[\"ESG Reporting\",\"Scope 3 emissions\",\"SB 253\",\"sustainability compliance\",\"U.S. companies\",\"California climate disclosure\"],\"articleSection\":[\"ESG Reporting\",\"North America\",\"Canada\",\"ESG Investment\",\"green skils\",\"green skills\",\"News\",\"Corporate sustainability\",\"Sustainability\",\"Sustainability Training\",\"Sustainability Reporting Services\",\"Strategies with an Impact\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cse-net.org\\\/california-sb253-scope3-baseline\\\/\",\"url\":\"https:\\\/\\\/cse-net.org\\\/california-sb253-scope3-baseline\\\/\",\"name\":\"California SB 253: Building a Credible Scope 3 Baseline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/california-sb253-scope3-baseline\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/california-sb253-scope3-baseline\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cse-net.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/blogs-v2-2025-5.png\",\"datePublished\":\"2025-09-02T12:00:31+00:00\",\"description\":\"Learn how U.S. companies can establish credible Scope 3 emissions baselines under California\u2019s SB 253. Discover key steps and data challenges.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/california-sb253-scope3-baseline\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cse-net.org\\\/california-sb253-scope3-baseline\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cse-net.org\\\/california-sb253-scope3-baseline\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cse-net.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/blogs-v2-2025-5.png\",\"contentUrl\":\"https:\\\/\\\/cse-net.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/blogs-v2-2025-5.png\",\"width\":840,\"height\":560,\"caption\":\"SB 253 Scope 3 baseline\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cse-net.org\\\/california-sb253-scope3-baseline\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cse-net.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"California SB 253 Perspectives: How to Create a Credible Baseline for Scope 3 Emissions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cse-net.org\\\/#website\",\"url\":\"https:\\\/\\\/cse-net.org\\\/\",\"name\":\"Center for Sustainbability & Excellence\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cse-net.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cse-net.org\\\/#organization\",\"name\":\"CSE\",\"url\":\"https:\\\/\\\/cse-net.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cse-net.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cse-net.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cse-logo-n.png\",\"contentUrl\":\"https:\\\/\\\/cse-net.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cse-logo-n.png\",\"width\":1200,\"height\":675,\"caption\":\"CSE\"},\"image\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Centre.for.Sustainability.and.Excellence\\\/\",\"https:\\\/\\\/x.com\\\/CSE_network\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/nikos-avlonas-81ab3410\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CSEorg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cse-net.org\\\/#\\\/schema\\\/person\\\/3615f0465d5060787c50f34130070382\",\"name\":\"cseadm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/772d54c2c50c66bb1066610c78ec69a846e22fb6547dc313273bc0b2a4bd4429?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/772d54c2c50c66bb1066610c78ec69a846e22fb6547dc313273bc0b2a4bd4429?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/772d54c2c50c66bb1066610c78ec69a846e22fb6547dc313273bc0b2a4bd4429?s=96&d=mm&r=g\",\"caption\":\"cseadm\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Californie SB 253 : Construire une base de r\u00e9f\u00e9rence cr\u00e9dible pour le champ d'application 3","description":"D\u00e9couvrez comment les entreprises am\u00e9ricaines peuvent \u00e9tablir des niveaux de r\u00e9f\u00e9rence cr\u00e9dibles pour les \u00e9missions de type 3 dans le cadre de la loi californienne SB 253. D\u00e9couvrez les \u00e9tapes cl\u00e9s et les d\u00e9fis en mati\u00e8re de donn\u00e9es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cse-net.org\/fr\/california-sb253-scope3-baseline\/","og_locale":"fr_FR","og_type":"article","og_title":"California SB 253: Building a Credible Scope 3 Baseline","og_description":"Learn how U.S. companies can establish credible Scope 3 emissions baselines under California\u2019s SB 253. Discover key steps and data challenges.","og_url":"https:\/\/cse-net.org\/fr\/california-sb253-scope3-baseline\/","og_site_name":"Center for Sustainbability &amp; Excellence","article_publisher":"https:\/\/www.facebook.com\/Centre.for.Sustainability.and.Excellence\/","article_published_time":"2025-09-02T12:00:31+00:00","og_image":[{"width":840,"height":560,"url":"https:\/\/cse-net.org\/wp-content\/uploads\/2025\/09\/blogs-v2-2025-5.png","type":"image\/png"}],"author":"cseadm","twitter_card":"summary_large_image","twitter_creator":"@CSE_network","twitter_site":"@CSE_network","twitter_misc":{"\u00c9crit par":"cseadm","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cse-net.org\/california-sb253-scope3-baseline\/#article","isPartOf":{"@id":"https:\/\/cse-net.org\/california-sb253-scope3-baseline\/"},"author":{"name":"cseadm","@id":"https:\/\/cse-net.org\/#\/schema\/person\/3615f0465d5060787c50f34130070382"},"headline":"California SB 253 Perspectives: How to Create a Credible Baseline for Scope 3 Emissions","datePublished":"2025-09-02T12:00:31+00:00","mainEntityOfPage":{"@id":"https:\/\/cse-net.org\/california-sb253-scope3-baseline\/"},"wordCount":684,"publisher":{"@id":"https:\/\/cse-net.org\/#organization"},"image":{"@id":"https:\/\/cse-net.org\/california-sb253-scope3-baseline\/#primaryimage"},"thumbnailUrl":"https:\/\/cse-net.org\/wp-content\/uploads\/2025\/09\/blogs-v2-2025-5.png","keywords":["ESG Reporting","Scope 3 emissions","SB 253","sustainability compliance","U.S. companies","California climate disclosure"],"articleSection":["ESG Reporting","North America","Canada","ESG Investment","green skils","green skills","News","Corporate sustainability","Sustainability","Sustainability Training","Sustainability Reporting Services","Strategies with an Impact"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cse-net.org\/california-sb253-scope3-baseline\/","url":"https:\/\/cse-net.org\/california-sb253-scope3-baseline\/","name":"Californie SB 253 : Construire une base de r\u00e9f\u00e9rence cr\u00e9dible pour le champ d'application 3","isPartOf":{"@id":"https:\/\/cse-net.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cse-net.org\/california-sb253-scope3-baseline\/#primaryimage"},"image":{"@id":"https:\/\/cse-net.org\/california-sb253-scope3-baseline\/#primaryimage"},"thumbnailUrl":"https:\/\/cse-net.org\/wp-content\/uploads\/2025\/09\/blogs-v2-2025-5.png","datePublished":"2025-09-02T12:00:31+00:00","description":"D\u00e9couvrez comment les entreprises am\u00e9ricaines peuvent \u00e9tablir des niveaux de r\u00e9f\u00e9rence cr\u00e9dibles pour les \u00e9missions de type 3 dans le cadre de la loi californienne SB 253. D\u00e9couvrez les \u00e9tapes cl\u00e9s et les d\u00e9fis en mati\u00e8re de donn\u00e9es.","breadcrumb":{"@id":"https:\/\/cse-net.org\/california-sb253-scope3-baseline\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cse-net.org\/california-sb253-scope3-baseline\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cse-net.org\/california-sb253-scope3-baseline\/#primaryimage","url":"https:\/\/cse-net.org\/wp-content\/uploads\/2025\/09\/blogs-v2-2025-5.png","contentUrl":"https:\/\/cse-net.org\/wp-content\/uploads\/2025\/09\/blogs-v2-2025-5.png","width":840,"height":560,"caption":"SB 253 Scope 3 baseline"},{"@type":"BreadcrumbList","@id":"https:\/\/cse-net.org\/california-sb253-scope3-baseline\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cse-net.org\/"},{"@type":"ListItem","position":2,"name":"California SB 253 Perspectives: How to Create a Credible Baseline for Scope 3 Emissions"}]},{"@type":"WebSite","@id":"https:\/\/cse-net.org\/#website","url":"https:\/\/cse-net.org\/","name":"Centre pour la durabilit\u00e9 et l'excellence","description":"","publisher":{"@id":"https:\/\/cse-net.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cse-net.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cse-net.org\/#organization","name":"CSE","url":"https:\/\/cse-net.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cse-net.org\/#\/schema\/logo\/image\/","url":"https:\/\/cse-net.org\/wp-content\/uploads\/2023\/12\/cse-logo-n.png","contentUrl":"https:\/\/cse-net.org\/wp-content\/uploads\/2023\/12\/cse-logo-n.png","width":1200,"height":675,"caption":"CSE"},"image":{"@id":"https:\/\/cse-net.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Centre.for.Sustainability.and.Excellence\/","https:\/\/x.com\/CSE_network","https:\/\/www.linkedin.com\/in\/nikos-avlonas-81ab3410\/","https:\/\/www.youtube.com\/user\/CSEorg"]},{"@type":"Person","@id":"https:\/\/cse-net.org\/#\/schema\/person\/3615f0465d5060787c50f34130070382","name":"cseadm","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/772d54c2c50c66bb1066610c78ec69a846e22fb6547dc313273bc0b2a4bd4429?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/772d54c2c50c66bb1066610c78ec69a846e22fb6547dc313273bc0b2a4bd4429?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/772d54c2c50c66bb1066610c78ec69a846e22fb6547dc313273bc0b2a4bd4429?s=96&d=mm&r=g","caption":"cseadm"}}]}},"_links":{"self":[{"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/posts\/13799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/comments?post=13799"}],"version-history":[{"count":1,"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/posts\/13799\/revisions"}],"predecessor-version":[{"id":13801,"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/posts\/13799\/revisions\/13801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/media\/13800"}],"wp:attachment":[{"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/media?parent=13799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/categories?post=13799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/tags?post=13799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}