{"id":2941,"date":"2022-05-30T17:31:33","date_gmt":"2022-05-30T14:31:33","guid":{"rendered":"https:\/\/cse-net.org\/case_studies\/netgear\/"},"modified":"2025-03-11T12:44:55","modified_gmt":"2025-03-11T09:44:55","slug":"netgear","status":"publish","type":"case_studies","link":"https:\/\/cse-net.org\/fr\/case_studies\/netgear\/","title":{"rendered":"NETGEAR"},"content":{"rendered":"","protected":false},"featured_media":3062,"parent":0,"menu_order":0,"template":"","sectors_cs":[1321],"services_cs":[],"class_list":["post-2941","case_studies","type-case_studies","status-publish","has-post-thumbnail","hentry","sectors_cs-technology"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NETGEAR - Center for Sustainbability &amp; Excellence<\/title>\n<meta name=\"description\" content=\"NETGEAR | Learn More\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cse-net.org\/fr\/case_studies\/netgear\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NETGEAR - Center for Sustainbability &amp; Excellence\" \/>\n<meta property=\"og:description\" content=\"NETGEAR | Learn More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cse-net.org\/fr\/case_studies\/netgear\/\" \/>\n<meta property=\"og:site_name\" content=\"Center for Sustainbability &amp; Excellence\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Centre.for.Sustainability.and.Excellence\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-11T09:44:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cse-net.org\/wp-content\/uploads\/2022\/05\/netgear-logo-nn.png\" \/>\n\t<meta property=\"og:image:width\" content=\"315\" \/>\n\t<meta property=\"og:image:height\" content=\"176\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CSE_network\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cse-net.org\\\/case_studies\\\/netgear\\\/\",\"url\":\"https:\\\/\\\/cse-net.org\\\/case_studies\\\/netgear\\\/\",\"name\":\"NETGEAR - Center for Sustainbability &amp; Excellence\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/case_studies\\\/netgear\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/case_studies\\\/netgear\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cse-net.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/netgear-logo-nn.png\",\"datePublished\":\"2022-05-30T14:31:33+00:00\",\"dateModified\":\"2025-03-11T09:44:55+00:00\",\"description\":\"NETGEAR | Learn More\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/case_studies\\\/netgear\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cse-net.org\\\/case_studies\\\/netgear\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cse-net.org\\\/case_studies\\\/netgear\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cse-net.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/netgear-logo-nn.png\",\"contentUrl\":\"https:\\\/\\\/cse-net.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/netgear-logo-nn.png\",\"width\":315,\"height\":176,\"caption\":\"NETGEAR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cse-net.org\\\/case_studies\\\/netgear\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cse-net.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Studies\",\"item\":\"https:\\\/\\\/cse-net.org\\\/case_studies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"NETGEAR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cse-net.org\\\/#website\",\"url\":\"https:\\\/\\\/cse-net.org\\\/\",\"name\":\"Center for Sustainbability & Excellence\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cse-net.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cse-net.org\\\/#organization\",\"name\":\"CSE\",\"url\":\"https:\\\/\\\/cse-net.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cse-net.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cse-net.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cse-logo-n.png\",\"contentUrl\":\"https:\\\/\\\/cse-net.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cse-logo-n.png\",\"width\":1200,\"height\":675,\"caption\":\"CSE\"},\"image\":{\"@id\":\"https:\\\/\\\/cse-net.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Centre.for.Sustainability.and.Excellence\\\/\",\"https:\\\/\\\/x.com\\\/CSE_network\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/nikos-avlonas-81ab3410\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CSEorg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NETGEAR - Centre pour la durabilit\u00e9 et l'excellence","description":"NETGEAR | En savoir plus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cse-net.org\/fr\/case_studies\/netgear\/","og_locale":"fr_FR","og_type":"article","og_title":"NETGEAR - Center for Sustainbability &amp; Excellence","og_description":"NETGEAR | Learn More","og_url":"https:\/\/cse-net.org\/fr\/case_studies\/netgear\/","og_site_name":"Center for Sustainbability &amp; Excellence","article_publisher":"https:\/\/www.facebook.com\/Centre.for.Sustainability.and.Excellence\/","article_modified_time":"2025-03-11T09:44:55+00:00","og_image":[{"width":315,"height":176,"url":"https:\/\/cse-net.org\/wp-content\/uploads\/2022\/05\/netgear-logo-nn.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@CSE_network","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cse-net.org\/case_studies\/netgear\/","url":"https:\/\/cse-net.org\/case_studies\/netgear\/","name":"NETGEAR - Centre pour la durabilit\u00e9 et l'excellence","isPartOf":{"@id":"https:\/\/cse-net.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cse-net.org\/case_studies\/netgear\/#primaryimage"},"image":{"@id":"https:\/\/cse-net.org\/case_studies\/netgear\/#primaryimage"},"thumbnailUrl":"https:\/\/cse-net.org\/wp-content\/uploads\/2022\/05\/netgear-logo-nn.png","datePublished":"2022-05-30T14:31:33+00:00","dateModified":"2025-03-11T09:44:55+00:00","description":"NETGEAR | En savoir plus","breadcrumb":{"@id":"https:\/\/cse-net.org\/case_studies\/netgear\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cse-net.org\/case_studies\/netgear\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cse-net.org\/case_studies\/netgear\/#primaryimage","url":"https:\/\/cse-net.org\/wp-content\/uploads\/2022\/05\/netgear-logo-nn.png","contentUrl":"https:\/\/cse-net.org\/wp-content\/uploads\/2022\/05\/netgear-logo-nn.png","width":315,"height":176,"caption":"NETGEAR"},{"@type":"BreadcrumbList","@id":"https:\/\/cse-net.org\/case_studies\/netgear\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cse-net.org\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/cse-net.org\/case_studies\/"},{"@type":"ListItem","position":3,"name":"NETGEAR"}]},{"@type":"WebSite","@id":"https:\/\/cse-net.org\/#website","url":"https:\/\/cse-net.org\/","name":"Centre pour la durabilit\u00e9 et l'excellence","description":"","publisher":{"@id":"https:\/\/cse-net.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cse-net.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cse-net.org\/#organization","name":"CSE","url":"https:\/\/cse-net.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cse-net.org\/#\/schema\/logo\/image\/","url":"https:\/\/cse-net.org\/wp-content\/uploads\/2023\/12\/cse-logo-n.png","contentUrl":"https:\/\/cse-net.org\/wp-content\/uploads\/2023\/12\/cse-logo-n.png","width":1200,"height":675,"caption":"CSE"},"image":{"@id":"https:\/\/cse-net.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Centre.for.Sustainability.and.Excellence\/","https:\/\/x.com\/CSE_network","https:\/\/www.linkedin.com\/in\/nikos-avlonas-81ab3410\/","https:\/\/www.youtube.com\/user\/CSEorg"]}]}},"_links":{"self":[{"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/case_studies\/2941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/case_studies"}],"about":[{"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/types\/case_studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/media\/3062"}],"wp:attachment":[{"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/media?parent=2941"}],"wp:term":[{"taxonomy":"sectors_cs","embeddable":true,"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/sectors_cs?post=2941"},{"taxonomy":"services_cs","embeddable":true,"href":"https:\/\/cse-net.org\/fr\/wp-json\/wp\/v2\/services_cs?post=2941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}